{"id":31108,"date":"2018-05-01T05:02:20","date_gmt":"2018-05-01T05:02:20","guid":{"rendered":"https:\/\/hongo.themezaa.com\/?page_id=3"},"modified":"2021-03-09T20:18:25","modified_gmt":"2021-03-09T19:18:25","slug":"polityka_prywatnosci","status":"publish","type":"page","link":"https:\/\/headwear.com.pl\/it\/polityka_prywatnosci\/","title":{"rendered":"Informativa sulla privacy"},"content":{"rendered":"<section class=\"vc_row wpb_row vc_row-fluid  vc_custom_1568290043072    hongo_responsive_1568290043082\"><div class=\"wpb_column vc_column_container col-xs-mobile-fullwidth vc_col-sm-12\"><div class=\"vc_column-inner vc_custom_1564120821420  hongo_responsive_1564120821424\"><div class=\"wpb_wrapper\"><div class=\"alt-font heading-style-1 vc_custom_1615316950024  hongo_responsive_1615316950025 heading-1 hongo-section-heading hongo_font_1615316950023\">Informativa sulla privacy - Headwear Professionals<\/div><div class=\"text-block-content hongo-text-block-1 vc_custom_1615317502001 last-paragraph-no-margin\"><p style=\"text-align: center;\"><strong>1<br \/>\nDisposizioni generali<\/strong><\/p>\n<ol>\n<li>La presente Informativa sulla privacy illustra le modalit\u00e0 di raccolta e utilizzo dei dati personali da parte nostra in conformit\u00e0 con le disposizioni del Regolamento (UE) del Parlamento europeo e del Consiglio del 27 aprile 2016 relativo alla protezione delle persone fisiche con riguardo al trattamento dei dati personali, nonch\u00e9 alla libera circolazione di tali dati e che abroga la direttiva 95\/46\/CE (di seguito denominato GDPR).<\/li>\n<li>Descriviamo per quale scopo e su quale base trattiamo i vostri dati personali, nonch\u00e9 quali diritti vi spettano in relazione al trattamento dei dati da parte nostra.<\/li>\n<li>I dati personali sono tutte le informazioni che possono identificarla, ovvero nome e cognome, numero di telefono, indirizzo e-mail e indirizzo di consegna degli acquisti.<\/li>\n<li>Il responsabile del trattamento dei dati personali \u00e8 Headwear PL Sp.z o.o. Sp. j., ul. S\u0142oneczna 4, 06-100 Pu\u0142tusk, che gestisce il negozio online headwear.com.pl all'indirizzo www.headwear.com.pl.<\/li>\n<li>Raccogliamo i dati personali nella misura minima possibile. Nel raccogliere tali dati, cerchiamo di garantirne l'affidabilit\u00e0 e l'attualit\u00e0. Se i dati personali raccolti non sono pi\u00f9 necessari per lo scopo previsto e non sussiste alcun obbligo legale di conservarli, cerchiamo, per quanto possibile, di eliminarli, distruggerli o renderli definitivamente non associabili a una persona specifica.<\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong>2<br \/>\nQuali dati personali raccogliamo?<\/strong><\/p>\n<p>Raccogliamo direttamente da voi i seguenti tipi di dati personali:<\/p>\n<ol>\n<li>\n<ul>\n<li><strong>Tramite il modulo di contatto (nella scheda \u201cContatti\u201d o \u201cRichiedi informazioni sul prodotto\u201d)\u00a0<\/strong>: nome e cognome, indirizzo e-mail, numero di telefono. Li utilizziamo esclusivamente per ricontattarvi e rispondere alle vostre richieste.<\/li>\n<li><strong>Tramite il modulo di registrazione\u00a0<\/strong>: nome e cognome, indirizzo e-mail, numero di telefono, indirizzo IP, nonch\u00e9 dati relativi all'indirizzo di consegna della merce (nome del destinatario, via, numero civico, numero dell'appartamento, codice postale, citt\u00e0, paese). Questi dati sono necessari per creare un account ed evadere gli ordini da voi effettuati, nonch\u00e9 per la registrazione delle vendite.<\/li>\n<li><strong>Tramite il modulo di iscrizione alla newsletter\u00a0<\/strong>: indirizzo e-mail. I dati cos\u00ec ottenuti vengono utilizzati esclusivamente per l'invio di informazioni commerciali (ad esempio su novit\u00e0 o promozioni).<\/li>\n<li><strong>Tramite il carrello degli ordini (effettuazione dell'ordine \/ prenotazione)\u00a0<\/strong>: nome e cognome; indirizzo e-mail, numero di telefono e dati di recapito per la consegna della merce (nome del destinatario, via, numero civico, numero dell'appartamento, codice postale, citt\u00e0, paese), esclusivamente in relazione alla stipula di un contratto di compravendita con il nostro negozio. In questo caso, i dati personali vengono trattati esclusivamente per l'evasione dell'ordine\/prenotazione e solo nella misura necessaria alla corretta esecuzione del contratto di compravendita della merce.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong>3<br \/>\nQuali sono i vostri diritti ai sensi del GDPR?<\/strong><\/p>\n<p>In relazione al trattamento dei vostri dati personali da parte di Headwear Professionals, avete una serie di diritti derivanti dal\u00a0<strong>\u201eRODO\u201d<\/strong>, in particolare:<\/p>\n<ol>\n<li><strong>Diritto di accesso<\/strong>\u00a0\u2013 in base a tale diritto, avete il diritto di ottenere la conferma che i vostri dati siano effettivamente trattati dal Negozio. Se i dati sono effettivamente trattati, avete il diritto di ottenere da noi le seguenti informazioni:\n<ul>\n<li>finalit\u00e0 per cui vengono trattati i dati personali (ad es. esecuzione del contratto, ecc.),<\/li>\n<li>categorie di dati personali soggetti a trattamento (ad es. nome, cognome, indirizzo);<\/li>\n<li>informazioni sui destinatari o sulle categorie di destinatari ai quali i dati personali sono stati o saranno comunicati, in particolare sui destinatari che si trovano al di fuori dell'UE (i cosiddetti paesi terzi);<\/li>\n<li>se possibile, il periodo di conservazione previsto dei dati personali e, qualora ci\u00f2 non sia possibile, i criteri utilizzati per determinare tale periodo;<\/li>\n<li>informazioni sui diritti che vi spettano, ovvero il diritto di richiedere al titolare del trattamento la rettifica, la cancellazione o la limitazione del trattamento dei dati e di opporvi (ovviamente, purch\u00e9 tali diritti specifici siano applicabili nel caso specifico);<\/li>\n<li>informazioni sul diritto di presentare reclamo all'autorit\u00e0 di controllo;<\/li>\n<li>informazioni sul processo decisionale automatizzato, compresa la profilazione, e informazioni rilevanti sulle regole di tale processo, nonch\u00e9 sull'importanza e sulle conseguenze previste di tale trattamento per l'interessato.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Il diritto alla cancellazione dei dati, il cosiddetto diritto all'oblio<\/strong>\u00a0\u2013 avete il diritto di richiedere al Negozio la cancellazione immediata dei dati personali, se si verifica una delle seguenti circostanze:\n<ul>\n<li>i dati personali non sono pi\u00f9 necessari per le finalit\u00e0 per cui sono stati raccolti o trattati in altro modo;<\/li>\n<li>revoca il consenso su cui si basava il trattamento e non sussiste alcun altro fondamento giuridico per il trattamento;<\/li>\n<li>lei si opponga al trattamento e non sussistano motivi legittimi prevalenti per il trattamento. A quel punto i suoi dati personali saranno cancellati dai nostri archivi;<\/li>\n<li>i dati personali sono stati trattati in modo illecito;<\/li>\n<li>la cancellazione dei dati personali \u00e8 necessaria per adempiere a un obbligo legale.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Diritto alla limitazione del trattamento<\/strong>\u00a0\u2013 in caso di richiesta in tal senso, il trattamento dei dati personali sar\u00e0 limitato alla sola conservazione nei seguenti casi:\n<ul>\n<li>contestate la correttezza dei dati personali \u2013 per un periodo che consenta al titolare del trattamento di verificarne la correttezza;<\/li>\n<li>il trattamento \u00e8 illegale e invece della cancellazione richiedete la limitazione dell'utilizzo dei dati personali;<\/li>\n<li>il responsabile del trattamento non ha pi\u00f9 bisogno dei dati personali per gli scopi per cui sono stati trattati, ma sono necessari all'interessato per l'accertamento, l'esercizio o la difesa di un diritto in sede giudiziaria;<\/li>\n<li>avete presentato opposizione al trattamento, che sar\u00e0 efficace nel momento in cui sar\u00e0 chiarito se l'opposizione \u00e8 giustificata.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Diritto di rettifica<\/strong>\u00a0\u2013 avete il diritto di richiederci la rettifica immediata dei vostri dati personali inesatti. Inoltre, tenendo conto delle finalit\u00e0 del trattamento, avete il diritto di richiedere l'integrazione dei dati personali incompleti.<\/li>\n<li><strong>Diritto di presentare reclamo<\/strong>\u00a0\u2013 avete inoltre il diritto di presentare un reclamo all'autorit\u00e0 di controllo competente responsabile della protezione dei dati. L'autorit\u00e0 di controllo competente in Polonia \u00e8 l'Ufficio per la protezione dei dati personali. Headwear Professionals, in qualit\u00e0 di titolare del trattamento dei dati, \u00e8 responsabile dell'attuazione di tali diritti in conformit\u00e0 con le disposizioni di legge vigenti. Per qualsiasi domanda o richiesta relativa alla portata e all'esercizio dei diritti, nonch\u00e9 alla necessit\u00e0 di avvalersi di un determinato diritto in materia di protezione dei dati personali, vi preghiamo di contattare\u00a0<strong>contatto con il Responsabile della protezione dei dati hpl@headwear.com.pl<\/strong><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong>4<br \/>\nAmbito del trattamento dei dati<\/strong><\/p>\n<p>Trattiamo i dati personali solo quando:<\/p>\n<ol>\n<li>\n<ul>\n<li>Le viene chiesto di acconsentire al trattamento dei dati per lo scopo indicato (art. 6, comma 1, lettera a del GDPR), ad esempio per rispondere alla Sua richiesta.<\/li>\n<li>il trattamento \u00e8 necessario per adempiere agli obblighi nei vostri confronti (art. 6, par. 1, lett. b del GDPR), se siete o sarete parte di un contratto relativo all'acquisto di beni nel nostro negozio e all'adozione di misure su richiesta della persona interessata.<\/li>\n<li>il trattamento \u00e8 necessario per adempiere agli obblighi legali o \u00e8 espressamente previsto dalla legge (art. 6, paragrafo 1, lettera c) del GDPR), ad esempio nel caso in cui sia necessario fornire dati personali alle autorit\u00e0 statali e per la tenuta dei registri fiscali.<\/li>\n<li>il trattamento \u00e8 necessario per il perseguimento dei legittimi interessi del titolare del trattamento o di terzi e non pregiudica in modo rilevante i diritti e le libert\u00e0 fondamentali dell'interessato (articolo 6, paragrafo 1, lettera f) del GDPR), ad esempio per l'esercizio o la difesa di un diritto in sede giudiziaria da parte del titolare del trattamento o di terzi, nonch\u00e9, tra l'altro, per finalit\u00e0 statistiche (compresa l'analisi e la profilazione dei dati).<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong>5<br \/>\nCondivisione dei dati personali<\/strong><\/p>\n<ol>\n<li>Headwear Professionals condivide i vostri dati personali solo con soggetti e organizzazioni che li proteggono e agiscono in conformit\u00e0 con le leggi vigenti in materia di protezione dei dati personali.<\/li>\n<li>I dati personali vengono raccolti solo se ci vengono forniti dall'utente, ad esempio compilando un modulo o inviando un'e-mail, nell'ambito di un ordine di beni, servizi o richieste.<\/li>\n<li>I tuoi dati possono essere trasmessi ai seguenti destinatari:\n<ul>\n<li>operatori postali, corrieri e fornitori, qualora ci\u00f2 sia necessario per l'esecuzione della consegna a vostro favore;<\/li>\n<li>soggetti che svolgono attivit\u00e0 di consulenza e revisione contabile;<\/li>\n<li>agenzie di marketing, se otteniamo il vostro consenso all'utilizzo dei dati per l'invio di informazioni commerciali o altre comunicazioni di marketing, oppure se ci\u00f2 \u00e8 consentito sulla base di un interesse legittimo del titolare del trattamento;<\/li>\n<li>soggetti che gestiscono pagamenti elettronici o carte di pagamento nella misura necessaria per gestire i pagamenti effettuati dal Cliente;<\/li>\n<li>fornitori di servizi che forniscono all'amministratore soluzioni tecniche e informatiche che consentono la gestione del negozio online e dei servizi forniti tramite esso (in particolare fornitori di software, fornitori di posta elettronica e hosting);<\/li>\n<li>i dati possono anche essere trasmessi a soggetti o istituzioni autorizzati a ottenerli in base alla legge vigente, ad esempio alle autorit\u00e0 di polizia in caso di richiesta di accesso ai dati su base giuridica adeguata (ad esempio per le esigenze di un procedimento penale in corso);<\/li>\n<li>ad altri soggetti, se ci\u00f2 risulti dagli accordi presi con voi.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<p>I soggetti sopra indicati non decidono autonomamente in merito alle modalit\u00e0 di trattamento dei dati personali dell'utente. Il trattamento dei dati personali da parte loro avviene solo nella misura necessaria allo svolgimento dell'attivit\u00e0 del titolare del trattamento e non andr\u00e0 oltre gli scopi indicati al \u00a7 4. Headwear Professionals stipula contratti di affidamento con i suddetti fornitori di servizi al fine di proteggere la vostra privacy. In linea di principio, tali fornitori di servizi possono trattare i dati in qualit\u00e0 di responsabili del trattamento, accedendo ai dati dell'utente solo nella misura e per il periodo necessario alla realizzazione di un determinato servizio.<\/p>\n<p>Nell'ambito della Politica sulla privacy adottata, Headwear Professionals si impegna a non vendere i dati personali dei clienti.<\/p>\n<p style=\"text-align: center;\"><strong>6<br \/>\nDecisioni automatizzate e profilazione<\/strong><\/p>\n<ol>\n<li>I tuoi dati personali vengono trattati in modo automatizzato e possono essere profilati.<\/li>\n<li>Potete opporvi alla profilazione in qualsiasi momento. Vi preghiamo tuttavia di tenere presente che grazie alla profilazione saremo in grado di adattare meglio i risultati di ricerca e gli annunci pubblicitari alle vostre preferenze.<\/li>\n<li>Dal momento della presentazione dell'opposizione, non siamo pi\u00f9 autorizzati a trattare tali dati personali, a meno che non siamo in grado di dimostrare l'esistenza di motivi legittimi e giustificati per il trattamento, che prevalgono sugli interessi, i diritti e le libert\u00e0 dell'interessato, o motivi per determinare, perseguire o difendere un diritto in sede giudiziaria.<\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong>7<br \/>\nTrasferimento verso paesi terzi<\/strong><\/p>\n<ol>\n<li>Se trasmettiamo dati personali a destinatari al di fuori dello Spazio economico europeo (SEE), ci\u00f2 avviene solo se la Commissione europea ha confermato un livello adeguato di protezione dei dati in relazione a tale paese terzo.<\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong>8<br \/>\nProtezione dei dati personali<\/strong><\/p>\n<ol>\n<li>Headwear Professionals adotta misure tecniche e organizzative che garantiscono la protezione del trattamento dei dati personali adeguata ai rischi e alle categorie di dati, e in particolare protegge i dati personali.<\/li>\n<li>L'accesso ai dati personali \u00e8 consentito esclusivamente alle persone autorizzate al loro trattamento e tenute a mantenerne la riservatezza. Tutti i soggetti incaricati del trattamento dei dati personali sulla base di un contratto sono tenuti a proteggerli adottando misure di sicurezza adeguate e non potranno trasmettere i vostri dati senza il nostro consenso e a nostra insaputa.<\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong>9<br \/>\nPeriodo di conservazione<\/strong><\/p>\n<p>Il periodo di trattamento dei vostri dati personali dipende dallo scopo per cui vengono trattati.<\/p>\n<ol>\n<li><strong>Evasione degli ordini<\/strong>: Nella misura in cui i vostri dati personali vengono trattati per l'evasione degli ordini, li tratteremo per tutta la durata del contratto relativo alla transazione, ma potremo prorogare tale periodo per la durata del termine di prescrizione dei vostri diritti, qualora il trattamento di tali dati sia necessario per determinare o far valere diritti legali, nonch\u00e9 per difenderci da tali diritti.<\/li>\n<li><strong>Raccolta dei dati di registrazione del cliente<\/strong>: Fino al momento della presentazione di una richiesta esplicita di cancellazione del vostro account cliente, tali dati saranno trattati dal nostro Negozio in modo limitato, limitandosi esclusivamente alla loro conservazione. Tali dati saranno conservati esclusivamente per le esigenze di altri contratti di acquisto-vendita di prodotti che potete stipulare tramite la nostra piattaforma internet.<\/li>\n<li><strong>Conservazione della documentazione ai fini della dimostrazione dell'adempimento degli obblighi previsti dalla legge, in particolare dalla legge sulla contabilit\u00e0 e dalla legge sull'ordinamento tributario.<\/strong>: Il periodo indicato nelle disposizioni di legge applicabili \u2013 di norma si tratta di periodi di 5 anni, calcolati a partire dalla fine dell'anno solare in cui, ad esempio, \u00e8 stata emessa la fattura.<\/li>\n<li><strong>Indagine o difesa dei diritti che possono essere fatti valere dall'amministratore o che possono essere fatti valere nei confronti dell'amministratore<\/strong>: I dati sono conservati per il periodo di validit\u00e0 dell'interesse legittimo perseguito dal titolare del trattamento, ma non oltre il termine di prescrizione dei diritti nei confronti dell'interessato, in relazione all'attivit\u00e0 commerciale svolta dal titolare del trattamento. Il termine di prescrizione \u00e8 stabilito dalla legge, in particolare dal codice civile (il termine di prescrizione di base per i crediti relativi all'attivit\u00e0 economica \u00e8 di tre anni, mentre per i contratti di vendita \u00e8 di due anni).<\/li>\n<li><strong>Modulo di contatto<\/strong>: Fino alla revoca del consenso<\/li>\n<li><strong>Attivit\u00e0 statistiche (compresa l'analisi e la profilazione dei dati)<\/strong>: Fino al momento della presentazione dell'opposizione<\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong>10<br \/>\nDisposizioni finali<\/strong><\/p>\n<ol>\n<li>In caso di domande, riserve o dubbi relativi al contenuto della presente Informativa sulla privacy o alle modalit\u00e0 di trattamento dei dati personali, nonch\u00e9 in caso di reclami relativi a tali questioni, inviare un'e-mail all'indirizzo indicato al \u00a7 3 della presente Informativa.<\/li>\n<li>Vi invitiamo inoltre, prima di presentare un reclamo, a contattare preventivamente il titolare del trattamento al fine di risolvere nel modo pi\u00f9 rapido e conveniente possibile qualsiasi questione relativa ai vostri dati personali e, se possibile, a chiarire i dubbi o risolvere il problema sorto.<\/li>\n<li>Da parte nostra, vi ringraziamo per la fiducia accordataci e faremo tutto il possibile per garantire la sicurezza dei vostri dati e il loro trattamento in conformit\u00e0 con la legge vigente.<\/li>\n<li>Headwear Professionals si riserva il diritto di apportare le modifiche e gli aggiornamenti necessari alla presente Informativa sulla privacy pubblicando il nuovo contenuto sul nostro sito web. Una volta apportate le modifiche, l'Informativa sulla privacy verr\u00e0 pubblicata sul sito con una nuova data.<\/li>\n<\/ol>\n<\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"Polityka prywatno\u015bci - Headwear Professionals1 Postanowienia og\u00f3lne Niniejsza Polityka Prywatno\u015bci wyja\u015bnia zasady zbierania i wykorzystywania przez nas danych osobowych zgodnie z przepisami rozporz\u0105dzenia Parlamentu Europejskiego i Rady (UE) z dnia 27 kwietnia 2016 r. w sprawie ochrony os\u00f3b fizycznych w zwi\u0105zku z przetwarzaniem danych osobowych i w sprawie swobodnego przep\u0142ywu takich danych oraz uchylenia dyrektywy 95\/46\/WE (zwany dalej RODO). Opisujemy w jakim celu i na jakiej podstawie przetwarzamy Pa\u0144stwa dane osobowe, a tak\u017ce jakie prawa przys\u0142uguj\u0105 Pa\u0144stwu w zwi\u0105zku z przetwarzaniem przez nas danych. Dane osobowe to wszelkie informacje, kt\u00f3re mog\u0105 Pani\u0105\/Pana identyfikowa\u0107 tj. imi\u0119 i nazwisko, numer telefonu, adres poczty elektronicznej i adres do dor\u0119czenia zakup\u00f3w. Administratorem Pa\u0144stwa danych osobowych jest Headwear PL Sp.z o.o. Sp. j., ul. S\u0142oneczna 4, 06-100 Pu\u0142tusk, kt\u00f3ra prowadzi sklep internetowy headwear.com.pl dzia\u0142aj\u0105cy pod adresem www.headwear.com.pl. Dane osobowe zbieramy w minimalnym mo\u017cliwym zakresie. Przy zbieraniu tych danych staramy si\u0119 zapewni\u0107 ich rzetelno\u015b\u0107 i aktualno\u015b\u0107. Je\u015bli zebrane dane osobowe przestan\u0105 by\u0107 niezb\u0119dne w danym celu i nie ma prawnego obowi\u0105zku ich przechowywania, w\u00f3wczas w miar\u0119 mo\u017cliwo\u015bci staramy si\u0119 je usun\u0105\u0107, zniszczy\u0107 lub trwale uniemo\u017cliwi\u0107 ich powi\u0105zanie z okre\u015blon\u0105 osob\u0105. 2 Jakie dane osobowe zbieramy? Zbieramy od Pa\u0144stwa bezpo\u015brednio nast\u0119puj\u0105ce rodzaje danych osobowych: Poprzez formularz kontaktowy...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Polityka prywatno\u015bci - Headwear Professionals<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/headwear.com.pl\/it\/polityka_prywatnosci\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Polityka prywatno\u015bci - Headwear Professionals\" \/>\n<meta property=\"og:url\" content=\"https:\/\/headwear.com.pl\/it\/polityka_prywatnosci\/\" \/>\n<meta property=\"og:site_name\" content=\"Headwear Professionals\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HeadwearPolska\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-09T19:18:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/headwear.com.pl\/polityka_prywatnosci\/\",\"url\":\"https:\/\/headwear.com.pl\/polityka_prywatnosci\/\",\"name\":\"Polityka prywatno\u015bci - Headwear Professionals\",\"isPartOf\":{\"@id\":\"https:\/\/headwear.com.pl\/fr\/#website\"},\"datePublished\":\"2018-05-01T05:02:20+00:00\",\"dateModified\":\"2021-03-09T19:18:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/headwear.com.pl\/polityka_prywatnosci\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/headwear.com.pl\/polityka_prywatnosci\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/headwear.com.pl\/polityka_prywatnosci\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/headwear.com.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Polityka prywatno\u015bci\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/headwear.com.pl\/fr\/#website\",\"url\":\"https:\/\/headwear.com.pl\/fr\/\",\"name\":\"Headwear Professionals\",\"description\":\"Produkcj\u0105 czapek reklamowych zajmujemy si\u0119 od 1974 roku. Pracujemy tylko z agencjami reklamowymi\",\"publisher\":{\"@id\":\"https:\/\/headwear.com.pl\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/headwear.com.pl\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/headwear.com.pl\/fr\/#organization\",\"name\":\"Headwear Professionals\",\"url\":\"https:\/\/headwear.com.pl\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/headwear.com.pl\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/headwear.com.pl\/wp-content\/uploads\/2024\/05\/Headwear_COLOR_RGB_logo.jpg\",\"contentUrl\":\"https:\/\/headwear.com.pl\/wp-content\/uploads\/2024\/05\/Headwear_COLOR_RGB_logo.jpg\",\"width\":1786,\"height\":1263,\"caption\":\"Headwear Professionals\"},\"image\":{\"@id\":\"https:\/\/headwear.com.pl\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/HeadwearPolska\",\"https:\/\/www.linkedin.com\/company\/headwearpolska\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informativa sulla privacy - Headwear Professionals","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/headwear.com.pl\/it\/polityka_prywatnosci\/","og_locale":"it_IT","og_type":"article","og_title":"Polityka prywatno\u015bci - Headwear Professionals","og_url":"https:\/\/headwear.com.pl\/it\/polityka_prywatnosci\/","og_site_name":"Headwear Professionals","article_publisher":"https:\/\/www.facebook.com\/HeadwearPolska","article_modified_time":"2021-03-09T19:18:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/headwear.com.pl\/polityka_prywatnosci\/","url":"https:\/\/headwear.com.pl\/polityka_prywatnosci\/","name":"Informativa sulla privacy - Headwear Professionals","isPartOf":{"@id":"https:\/\/headwear.com.pl\/fr\/#website"},"datePublished":"2018-05-01T05:02:20+00:00","dateModified":"2021-03-09T19:18:25+00:00","breadcrumb":{"@id":"https:\/\/headwear.com.pl\/polityka_prywatnosci\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/headwear.com.pl\/polityka_prywatnosci\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/headwear.com.pl\/polityka_prywatnosci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/headwear.com.pl\/"},{"@type":"ListItem","position":2,"name":"Polityka prywatno\u015bci"}]},{"@type":"WebSite","@id":"https:\/\/headwear.com.pl\/fr\/#website","url":"https:\/\/headwear.com.pl\/fr\/","name":"Headwear Professionals","description":"Produciamo tappi pubblicitari dal 1974. Lavoriamo solo con agenzie pubblicitarie","publisher":{"@id":"https:\/\/headwear.com.pl\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/headwear.com.pl\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/headwear.com.pl\/fr\/#organization","name":"Headwear Professionals","url":"https:\/\/headwear.com.pl\/fr\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/headwear.com.pl\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/headwear.com.pl\/wp-content\/uploads\/2024\/05\/Headwear_COLOR_RGB_logo.jpg","contentUrl":"https:\/\/headwear.com.pl\/wp-content\/uploads\/2024\/05\/Headwear_COLOR_RGB_logo.jpg","width":1786,"height":1263,"caption":"Headwear Professionals"},"image":{"@id":"https:\/\/headwear.com.pl\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HeadwearPolska","https:\/\/www.linkedin.com\/company\/headwearpolska"]}]}},"_links":{"self":[{"href":"https:\/\/headwear.com.pl\/it\/wp-json\/wp\/v2\/pages\/31108"}],"collection":[{"href":"https:\/\/headwear.com.pl\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/headwear.com.pl\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/headwear.com.pl\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/headwear.com.pl\/it\/wp-json\/wp\/v2\/comments?post=31108"}],"version-history":[{"count":0,"href":"https:\/\/headwear.com.pl\/it\/wp-json\/wp\/v2\/pages\/31108\/revisions"}],"wp:attachment":[{"href":"https:\/\/headwear.com.pl\/it\/wp-json\/wp\/v2\/media?parent=31108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}